{"id":144,"date":"2024-11-24T17:28:14","date_gmt":"2024-11-24T16:28:14","guid":{"rendered":"https:\/\/humcor.snlt.es\/?page_id=144"},"modified":"2025-08-03T17:28:41","modified_gmt":"2025-08-03T15:28:41","slug":"contact","status":"publish","type":"page","link":"https:\/\/humcor.snlt.es\/ca\/contact\/","title":{"rendered":"Contacte"},"content":{"rendered":"<div id=\"pl-144\"  class=\"panel-layout\" ><div id=\"pg-144-0\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-144-0-0\"  class=\"panel-grid-cell\" ><div id=\"panel-144-0-0-0\" class=\"so-panel widget widget_sow-editor panel-first-child panel-last-child\" data-index=\"0\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-editor so-widget-sow-editor-base\"\n\t\t\t\n\t\t><h3 class=\"widget-title\">Dades de contacte<\/h3>\n<div class=\"siteorigin-widget-tinymce textwidget\">\n\t<p>Pots contactar amb nosaltres utilitzant el formulari d'aquesta p\u00e0gina.<\/p>\n<p>Tamb\u00e9 pots utilitzar el nostre correu: <strong>info@humcor.snlt.es<\/strong>.<\/p>\n<\/div>\n<\/div><\/div><\/div><div id=\"pgc-144-0-1\"  class=\"panel-grid-cell\" ><div id=\"panel-144-0-1-0\" class=\"so-panel widget widget_sow-contact-form panel-first-child panel-last-child\" data-index=\"1\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-contact-form so-widget-sow-contact-form-default-e9e90134b3de-144\"\n\t\t\t\n\t\t><h3 class=\"widget-title\">Formulario de contacto<\/h3>\t<form\n\t\taction=\"\/ca\/wp-json\/wp\/v2\/pages\/144\"\n\t\tmethod=\"POST\"\n\t\tclass=\"sow-contact-form\"\n\t\tid=\"contact-form-822a\"\n\t>\n\n\t\t\n\t\t\t\t\t<div class=\"sow-form-field sow-form-field-name\">\n\t\t\t\t<label class=\"sow-form-field-label-above\" for=\"sow-contact-form-field-tu-nombre-1\">\n\t\t\t\t<strong>\n\t\t\t\t\tTu nombre\t\t\t\t\t\t\t\t\t<\/strong>\n\t\t\t<\/label>\n\t\t\t\t\t\t\t<div class=\"sow-field-container\">\n\t\t\t\t\t\t\t<input\n\t\t\ttype=\"text\"\n\t\t\tname=\"tu-nombre-1\"\n\t\t\tid=\"sow-contact-form-field-tu-nombre-1\"\n\t\t\tvalue=\"\"\n\t\t\tclass=\"sow-text-field\"\n\t\t\t\t\t\t\t\t\/>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"sow-form-field sow-form-field-email\">\n\t\t\t\t<label class=\"sow-form-field-label-above\" for=\"sow-contact-form-field-tu-correo-electronico-1\">\n\t\t\t\t<strong>\n\t\t\t\t\tTu correo electr\u00f3nico\t\t\t\t\t\t\t\t\t<\/strong>\n\t\t\t<\/label>\n\t\t\t\t\t\t\t<div class=\"sow-field-container\">\n\t\t\t\t\t\t\t<input\n\t\t\ttype=\"email\"\n\t\t\tname=\"tu-correo-electronico-1\"\n\t\t\tid=\"sow-contact-form-field-tu-correo-electronico-1\"\n\t\t\tvalue=\"\"\n\t\t\tclass=\"sow-text-field\"\t\t\t\t\t\t\t\t\/>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"sow-form-field sow-form-field-textarea\">\n\t\t\t\t<label class=\"sow-form-field-label-above\" for=\"sow-contact-form-field-mensaje-1\">\n\t\t\t\t<strong>\n\t\t\t\t\tMensaje\t\t\t\t\t\t\t\t\t<\/strong>\n\t\t\t<\/label>\n\t\t\t\t\t\t\t<div class=\"sow-field-container\">\n\t\t\t\t\t\t\t<textarea\n\t\t\tname=\"mensaje-1\"\n\t\t\tid=\"sow-contact-form-field-mensaje-1\"\n\t\t\trows=\"10\"\n\t\t\t\t\t\t\t\t><\/textarea>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<input\n\t\t\t\ttype=\"text\"\n\t\t\t\tname=\"sow-name\"\n\t\t\t\tclass=\"sow-text-field\"\n\t\t\t\tstyle=\"display: none !important; visibility: hidden !important;\"\n\t\t\t\tautocomplete=\"off\"\n\t\t\t\taria-hidden=\"true\"\n\t\t\t>\n\t\t\n\t\t\n\t\t<div class=\"sow-submit-wrapper \n\t\tsow-submit-styled\t\t\">\n\n\t\t\t<button\n\t\t\t\ttype=\"submit\"\n\t\t\t\tclass=\"sow-submit\n\t\t\t\t\t\t\t\t\"\n\t\t\t\tdata-js-key=\"c4ca4238a0b923820dcc509a6f75849b\" \t\t\t>\n\t\t\t\tEnviar mensaje\t\t\t<\/button>\n\t\t<\/div>\n\t\t\t\t<input\n\t\t\ttype=\"hidden\"\n\t\t\tname=\"instance_hash-1\"\n\t\t\tvalue=\"822a0745\"\n\t\t\/>\n\n\t\t<input type=\"hidden\" id=\"_wpnonce\" name=\"_wpnonce\" value=\"16fddfea2b\" \/><input type=\"hidden\" name=\"_wp_http_referer\" value=\"\/ca\/wp-json\/wp\/v2\/pages\/144\" \/>\t<\/form>\n\t<\/div><\/div><\/div><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Pots contactar amb nosaltres utilitzant el formulari d&#8217;aquesta p\u00e0gina. Tamb\u00e9 pots utilitzar el nostre correu: info@humcor.snlt.es.<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-144","page","type-page","status-publish","hentry","post"],"_links":{"self":[{"href":"https:\/\/humcor.snlt.es\/ca\/wp-json\/wp\/v2\/pages\/144","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/humcor.snlt.es\/ca\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/humcor.snlt.es\/ca\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/humcor.snlt.es\/ca\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/humcor.snlt.es\/ca\/wp-json\/wp\/v2\/comments?post=144"}],"version-history":[{"count":19,"href":"https:\/\/humcor.snlt.es\/ca\/wp-json\/wp\/v2\/pages\/144\/revisions"}],"predecessor-version":[{"id":147,"href":"https:\/\/humcor.snlt.es\/ca\/wp-json\/wp\/v2\/pages\/144\/revisions\/147"}],"wp:attachment":[{"href":"https:\/\/humcor.snlt.es\/ca\/wp-json\/wp\/v2\/media?parent=144"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}